{"id":29432,"date":"2025-12-04T14:04:29","date_gmt":"2025-12-04T19:04:29","guid":{"rendered":"https:\/\/quantumlifecycle.com\/uncategorized-fr_ca\/retablissement-des-forets-canada-un-profil\/"},"modified":"2025-12-04T14:04:29","modified_gmt":"2025-12-04T19:04:29","slug":"retablissement-des-forets-canada-un-profil","status":"publish","type":"post","link":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/","title":{"rendered":"R\u00e9tablissement des for\u00eats Canada : un profil"},"content":{"rendered":"<p><a href=\"https:\/\/www.forestsontario.ca\/planting\/programs\/forest-recovery-canada\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>Renouvellement des for\u00eats Canada<\/u><\/span><\/span><\/a> (FRC) est un organisme \u00e0 but non lucratif et caritatif d\u00e9di\u00e9 \u00e0 la r\u00e9duction du carbone et au reboisement du Canada. Il a plant\u00e9 plus de 23 millions de semis depuis 2004 et sensibilise \u00e9galement le public aux arbres. <\/p>\n<p><span lang=\"en-CA\"><b>Le saviez-vous?<\/b><\/span><\/p>\n<ul>\n<li>&#8230; que la feuille sur le drapeau canadien provient d\u2019un \u00e9rable \u00e0 sucre?<\/li>\n<li>&#8230; que chaque kg de bois s\u00e9ch\u00e9 stocke environ 1,65 kg de carbone provenant de l\u2019atmosph\u00e8re?<\/li>\n<li>&#8230; Qu\u2019un arbre en bonne sant\u00e9 stocke en moyenne 169 kg de carbone par ann\u00e9e?<\/li>\n<\/ul>\n<p>Le FRC est toujours \u00e0 la recherche de b\u00e9n\u00e9voles, de commanditaires et de donateurs pour aider \u00e0 garder les for\u00eats du Canada vertes et planter plus d\u2019arbres. Au-del\u00e0 de leur programme de b\u00e9n\u00e9volat, ils ont deux principaux programmes de plantation, un pour les propri\u00e9taires fonciers et un pour les commanditaires corporatifs. <\/p>\n<p>Le <a href=\"https:\/\/www.forestsontario.ca\/planting\/programs\/50-million-tree-program\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>programme de subventions pour les propri\u00e9taires fonciers<\/u><\/span><\/span><\/a> fait partie de l\u2019engagement du gouvernement de l\u2019Ontario \u00e0 planter 50 millions d\u2019arbres d\u2019ici 2025. Plus de 4 000 propri\u00e9taires fonciers y ont particip\u00e9 \u00e0 ce jour. Les avantages pour les propri\u00e9taires fonciers incluent l\u2019augmentation de la valeur de leurs terres, l\u2019am\u00e9lioration de la qualit\u00e9 de leur sol, l\u2019augmentation de l\u2019habitat faunique, l\u2019am\u00e9lioration des possibilit\u00e9s r\u00e9cr\u00e9atives, l\u2019am\u00e9lioration de la sant\u00e9 globale de l\u2019environnement et la cr\u00e9ation d\u2019un h\u00e9ritage durable.  <\/p>\n<p>Le programme corporatif FRC permet aux entreprises <a href=\"#partners\" rel=\"nofollow\"><u>commanditaires<\/u><\/a> de planter des arbres soit par don direct, soit par un don li\u00e9 aux ventes ou services de l\u2019entreprise. Un des commanditaires corporatifs du FRC est Quantum, qui a commenc\u00e9 \u00e0 soutenir le programme en 2016 lorsqu\u2019ils ont d\u00e9cid\u00e9 de donner un arbre pour chaque collecte de recyclage. \u00c0 ce jour, leurs dons sont responsables de la plantation de plus de 3 000 arbres \u2013 des arbres \u00e9tant ajout\u00e9s \u00e0 la for\u00eat chaque jour.  <\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2757\" src=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/Forests-Recovery-Canada.jpg\" alt=\"R\u00e9habilitation des for\u00eats Canada\" width=\"720\" height=\"405\" srcset=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/Forests-Recovery-Canada.jpg 720w, https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/Forests-Recovery-Canada-300x169.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>\u00ab Nous sommes enthousiastes \u00e0 l\u2019id\u00e9e de soutenir ce type d\u2019initiative verte parce qu\u2019elle contribue directement \u00e0 la r\u00e9duction du carbone et \u00e0 l\u2019environnement. D\u2019apr\u00e8s nos observations jusqu\u2019\u00e0 pr\u00e9sent cette ann\u00e9e, nous serons probablement responsables de la plantation de plusieurs milliers d\u2019arbres suppl\u00e9mentaires \u00e0 travers le pays pour 2018, et nous voulons avoir un impact encore plus grand sur l\u2019environnement \u00e0 l\u2019avenir \u00bb, affirme Clayton Miller.<\/p>\n<p>Il est bien connu que les arbres inhalent du dioxyde de carbone et \u00e9mettent de l\u2019oxyg\u00e8ne (le contraire de ce que font les humains), ce qui nettoie l\u2019air. Un arbre jeune peut consommer 11,8 kg de dioxyde de carbone par an, tandis qu\u2019un <a href=\"http:\/\/www.arborenvironmentalalliance.com\/carbon-tree-facts.asp\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>arbre mature<\/u><\/span><\/span><\/a> peut en consommer 21,8 kg. <a href=\"https:\/\/www.thoughtco.com\/how-much-oxygen-does-one-tree-produce-606785\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>Un hectare<\/u><\/span><\/span><\/a> d\u2019arbres produit assez d\u2019oxyg\u00e8ne pour 44 personnes pendant un an. <\/p>\n<p>Ainsi, les 3 000 arbres plant\u00e9s par le parrainage de Quantum consommeront 65 400 kg de dioxyde de carbone par ann\u00e9e lorsqu\u2019ils seront matures. C\u2019est un exploit qui m\u00e9rite d\u2019\u00eatre reconnu. <\/p>\n<p>En choisissant Quantum pour vos services de recyclage, vous nous aidez \u00e0 planter des milliers d\u2019arbres suppl\u00e9mentaires \u00e0 travers le Canada. Nous sommes reconnaissants et savons que nous ne pouvons pas y arriver sans vous \u00bb, ajoute Miller. <\/p>\n<p>Vous pouvez planifier un ramassage avec Quantum ici et aider \u00e0 faire du Canada un endroit plus propre et plus \u00e9cologique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantum envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario. <\/p>\n","protected":false},"author":3,"featured_media":29433,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.","om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_metasync_otto_title":"","_metasync_otto_description":"","_metasync_otto_keywords":"","_metasync_otto_og_title":"","_metasync_otto_og_description":"","_metasync_otto_twitter_title":"","_metasync_otto_twitter_description":"","rank_math_title":"","rank_math_description":"","_aioseo_title":"","_aioseo_description":"","_metasync_seo_title":"","_metasync_seo_desc":"","_metasync_breadcrumb_title":"","_metasync_primary_category":0,"_metasync_primary_product_cat":0,"_metasync_otto_disabled":"","_metasync_hreflang":"","_metasync_plugin_sync_ts":"","_metasync_robots_advanced":"","footnotes":""},"categories":[47],"tags":[],"class_list":{"0":"post-29432","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blogue","8":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling<\/title>\n<meta name=\"description\" content=\"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:description\" content=\"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/\" \/>\n<meta property=\"og:site_name\" content=\"Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Quantum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Quantum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/\"},\"author\":{\"name\":\"Quantum\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\"},\"headline\":\"R\u00e9tablissement des for\u00eats Canada : un profil\",\"datePublished\":\"2025-12-04T19:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/\"},\"wordCount\":554,\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/tree-Cropped.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/\",\"name\":\"R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/tree-Cropped.jpg\",\"datePublished\":\"2025-12-04T19:04:29+00:00\",\"description\":\"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/tree-Cropped.jpg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/tree-Cropped.jpg\",\"width\":1260,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/retablissement-des-forets-canada-un-profil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9tablissement des for\u00eats Canada : un profil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"name\":\"Quantum | ITAD & E-Waste Recycling\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\",\"name\":\"Quantum Lifecycle Partners LP\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"width\":2700,\"height\":848,\"caption\":\"Quantum Lifecycle Partners LP\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\",\"name\":\"Quantum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"caption\":\"Quantum\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling","description":"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/","og_locale":"fr_CA","og_type":"article","og_title":"R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling","og_description":"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.","og_url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/","og_site_name":"Quantum | ITAD &amp; E-Waste Recycling","og_image":[{"width":1260,"height":630,"url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg","type":"image\/jpeg"}],"author":"Quantum","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Quantum","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#article","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/"},"author":{"name":"Quantum","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda"},"headline":"R\u00e9tablissement des for\u00eats Canada : un profil","datePublished":"2025-12-04T19:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/"},"wordCount":554,"publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg","articleSection":["Blog"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/","url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/","name":"R\u00e9tablissement des for\u00eats Canada : un profil - Quantum | ITAD &amp; E-Waste Recycling","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#primaryimage"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg","datePublished":"2025-12-04T19:04:29+00:00","description":"Le recyclage soucieux de l\u2019environnement n\u2019est qu\u2019une partie de l\u2019engagement de Quantums envers l\u2019environnement. En soutenant l\u2019initiative de forestation du FRC, vous nous aidez aussi \u00e0 planter des arbres partout en Ontario.","breadcrumb":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#primaryimage","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/03\/tree-Cropped.jpg","width":1260,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/retablissement-des-forets-canada-un-profil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quantumlifecycle.com\/fr_CA\/"},{"@type":"ListItem","position":2,"name":"R\u00e9tablissement des for\u00eats Canada : un profil"}]},{"@type":"WebSite","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","name":"Quantum | ITAD & E-Waste Recycling","description":"","publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quantumlifecycle.com\/fr_CA\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization","name":"Quantum Lifecycle Partners LP","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","width":2700,"height":848,"caption":"Quantum Lifecycle Partners LP"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda","name":"Quantum","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","caption":"Quantum"}}]}},"_links":{"self":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/comments?post=29432"}],"version-history":[{"count":0,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media\/29433"}],"wp:attachment":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media?parent=29432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/categories?post=29432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/tags?post=29432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}