{"id":29398,"date":"2025-12-04T13:30:06","date_gmt":"2025-12-04T18:30:06","guid":{"rendered":"https:\/\/quantumlifecycle.com\/uncategorized-fr_ca\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/"},"modified":"2025-12-04T13:30:06","modified_gmt":"2025-12-04T18:30:06","slug":"lamelioration-continue-detre-une-philosophie-directrice-chez-quantum","status":"publish","type":"post","link":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/","title":{"rendered":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum"},"content":{"rendered":"<p><span lang=\"en-CA\">Cela fait un peu plus d\u2019un an que Quantum a emm\u00e9nag\u00e9 dans un nouveau b\u00e2timent et le PDG Gary Diamond consid\u00e8re ce d\u00e9m\u00e9nagement comme une preuve solide du succ\u00e8s continu du processus de modernisation qui fait partie de l\u2019entreprise depuis son ouverture en 2010.  <\/span><\/p>\n<p>\u00ab <span lang=\"en-CA\">Dans l\u2019industrie tr\u00e8s comp\u00e9titive du recyclage, l\u2019un de nos principaux \u00e9l\u00e9ments diff\u00e9renciateurs est l\u2019am\u00e9lioration continue \u00bb, affirme Diamond. \u00ab Chez Quantum, nous croyons fermement au <\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Kaizen\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><i><u>kaizen<\/u><\/i><\/span><\/span><\/a><span lang=\"en-CA\">, le terme japonais d\u00e9signant l\u2019am\u00e9lioration continue des affaires, et \u00e0 l\u2019implication de tous les employ\u00e9s \u2014 du PDG aux travailleurs de la cha\u00eene de production \u2014 dans les processus qui am\u00e9liorent la production et \u00e9liminent le gaspillage.<\/span> \u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1269 size-full\" src=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2018\/09\/Etl0uQvA-e1536904179930.jpeg\" alt=\"Entrep\u00f4t de recyclage de quart\" width=\"600\" height=\"400\"><\/p>\n<p><span lang=\"en-CA\"><b>Am\u00e9liorations r\u00e9centes chez Quantum<\/b><\/span><\/p>\n<p><span lang=\"en-CA\">Au cours de l\u2019ann\u00e9e suivant le d\u00e9m\u00e9nagement vers leur nouvelle installation de 125 000 pi\u00b2, Quantum a apport\u00e9 d\u2019autres am\u00e9liorations dans des domaines cl\u00e9s. Diamond r\u00e9sume ces changements comme une am\u00e9lioration de l\u2019efficacit\u00e9 en r\u00e9duisant les co\u00fbts, en am\u00e9liorant la coh\u00e9rence et la propret\u00e9 de la qualit\u00e9 des produits, ainsi qu\u2019en r\u00e9duisant les risques pour la sant\u00e9 et la s\u00e9curit\u00e9.    <\/span><\/p>\n<p><span lang=\"en-CA\">Plus pr\u00e9cis\u00e9ment, Quantum a :<\/span><\/p>\n<ul>\n<li><span lang=\"en-CA\">J\u2019ai install\u00e9 une ligne de d\u00e9chiquetage \u00e0 la fine pointe de la technologie avec plus de machines pour am\u00e9liorer l\u2019efficacit\u00e9 des co\u00fbts et la qualit\u00e9 de s\u00e9paration.<\/span><\/li>\n<li><span lang=\"en-CA\">J\u2019ai embauch\u00e9 un directeur \u00e0 temps plein des syst\u00e8mes informatiques et du d\u00e9veloppement pour aider le syst\u00e8me \u00e0 capturer et \u00e0 rendre compte des donn\u00e9es en temps r\u00e9el.  <\/span><\/li>\n<li><span lang=\"en-CA\">A introduit de nouvelles zones de triage pour affiner davantage les produits qu\u2019ils traitent et\/ou vendent.<\/span><\/li>\n<li><span lang=\"en-CA\">Introduction d\u2019une ligne de traitement d\u00e9di\u00e9e pour <\/span><a href=\"https:\/\/www.researchgate.net\/publication\/225241489_Recycling_of_LCD_Screens_in_Europe_-_State_of_the_Art_and_Challenges\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>les \u00e9crans \u00e0 \u00e9cran plat<\/u><\/span><\/span><\/a><span lang=\"en-CA\"> , alors que cette cat\u00e9gorie de recyclage continue de cro\u00eetre en pourcentage du volume re\u00e7u.<\/span><\/li>\n<li><span lang=\"en-CA\">Introduction de convoyeurs m\u00e9caniques au d\u00e9but du processus de tri afin d\u2019am\u00e9liorer l\u2019efficacit\u00e9 et de r\u00e9duire les risques pour la sant\u00e9 et la s\u00e9curit\u00e9.<\/span><\/li>\n<li><span lang=\"en-CA\">J\u2019ai am\u00e9lior\u00e9 l\u2019\u00e9clairage pour am\u00e9liorer l\u2019atmosph\u00e8re g\u00e9n\u00e9rale.<\/span><\/li>\n<li><span lang=\"en-CA\">Augmentation du nombre de chariots \u00e9l\u00e9vateurs \u00e9lectriques \u00e0 batterie.  <\/span><\/li>\n<li><span lang=\"en-CA\">Nous avons continu\u00e9 \u00e0 investir des ressources dans l\u2019optimisation du flux et de la disposition de l\u2019entrep\u00f4t.<\/span><\/li>\n<\/ul>\n<p><span lang=\"en-CA\"><b>Que devrais-je rechercher chez un recycleur?<\/b><\/span><\/p>\n<p><span lang=\"en-CA\">Les d\u00e9chets \u00e9lectroniques sont le type de d\u00e9chets \u00e0 la croissance la plus rapide dans les sites d\u2019enfouissement nord-am\u00e9ricains. Selon l\u2019Universit\u00e9 des Nations Unies, la <\/span><a href=\"https:\/\/www.sciencealert.com\/global-electronic-waste-growth-report-2017-significant-increase\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><span style=\"color: #0000ff;\"><span lang=\"en-CA\"><u>quantit\u00e9 de d\u00e9chets \u00e9lectroniques jet\u00e9s chaque<\/u><\/span><\/span><\/a><span lang=\"en-CA\"> ann\u00e9e repr\u00e9sente le poids de neuf grandes pyramides de Gizeh ou 4 500 tours Eiffel, il est donc logique de choisir une entreprise r\u00e9put\u00e9e pour vos besoins en recyclage qui fait le plus possible pour am\u00e9liorer l\u2019environnement. Quantum, avec son engagement envers l\u2019am\u00e9lioration continue gr\u00e2ce au mod\u00e8le kaizen, est une entreprise avec un plan \u00e9prouv\u00e9 pour aider l\u2019environnement. <\/span> <\/p>\n<p><span lang=\"en-CA\">Quantum est \u00e9galement <\/span>audit\u00e9 par un tiers<span lang=\"en-CA\"> chaque ann\u00e9e et enti\u00e8rement accr\u00e9dit\u00e9. Cela inclut la norme R2, une norme internationale de recyclage \u00e9lectronique ax\u00e9e sur la s\u00e9curit\u00e9 des donn\u00e9es, la conformit\u00e9 environnementale ainsi que la sant\u00e9 et s\u00e9curit\u00e9 au travail. De plus, leurs accr\u00e9ditations ISO 14001 et OHSAS 1800 offrent la tranquillit\u00e9 d\u2019esprit aux clients qui souhaitent savoir que les buts et objectifs pour la sant\u00e9 et la s\u00e9curit\u00e9 au travail\/les risques environnementaux sont fix\u00e9s et activement g\u00e9r\u00e9s. En fin de compte, cela rend Quantum plus \u00e9thique.<\/span><\/p>\n<p>Contactez Quantum d\u00e8s aujourd\u2019hui pour discuter de vos besoins en recyclage, grands ou petits, et rassurez-vous du choix que vous avez fait pour l\u2019avenir de la plan\u00e8te.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant qu\u2019entreprise qui vise le succ\u00e8s et l\u2019am\u00e9lioration continus, Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes \u00e0 se d\u00e9velopper. En se concentrant sur le d\u00e9veloppement continu de nouvelles m\u00e9thodes et les \u00e9volutions de l\u2019industrie des d\u00e9chets \u00e9lectroniques, parall\u00e8lement au d\u00e9veloppement personnel, Quantum cherche toujours \u00e0 am\u00e9liorer notre fa\u00e7on de fonctionner et \u00e0 s\u2019am\u00e9liorer nous-m\u00eames. <\/p>\n","protected":false},"author":3,"featured_media":29399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.","om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_metasync_otto_title":"","_metasync_otto_description":"","_metasync_otto_keywords":"","_metasync_otto_og_title":"","_metasync_otto_og_description":"","_metasync_otto_twitter_title":"","_metasync_otto_twitter_description":"","rank_math_title":"","rank_math_description":"","_aioseo_title":"","_aioseo_description":"","_metasync_seo_title":"","_metasync_seo_desc":"","_metasync_breadcrumb_title":"","_metasync_primary_category":0,"_metasync_primary_product_cat":0,"_metasync_otto_disabled":"","_metasync_hreflang":"","_metasync_plugin_sync_ts":"","_metasync_robots_advanced":"","footnotes":""},"categories":[47],"tags":[],"class_list":{"0":"post-29398","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blogue","8":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling<\/title>\n<meta name=\"description\" content=\"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:description\" content=\"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/\" \/>\n<meta property=\"og:site_name\" content=\"Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1268\" \/>\n\t<meta property=\"og:image:height\" content=\"634\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Quantum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Quantum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/\"},\"author\":{\"name\":\"Quantum\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\"},\"headline\":\"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum\",\"datePublished\":\"2025-12-04T18:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/p-Cropped.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/\",\"name\":\"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/p-Cropped.jpg\",\"datePublished\":\"2025-12-04T18:30:06+00:00\",\"description\":\"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/p-Cropped.jpg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/p-Cropped.jpg\",\"width\":1268,\"height\":634},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"name\":\"Quantum | ITAD & E-Waste Recycling\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\",\"name\":\"Quantum Lifecycle Partners LP\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"width\":2700,\"height\":848,\"caption\":\"Quantum Lifecycle Partners LP\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\",\"name\":\"Quantum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"caption\":\"Quantum\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling","description":"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/","og_locale":"fr_CA","og_type":"article","og_title":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling","og_description":"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.","og_url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/","og_site_name":"Quantum | ITAD &amp; E-Waste Recycling","og_image":[{"width":1268,"height":634,"url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg","type":"image\/jpeg"}],"author":"Quantum","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Quantum","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#article","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/"},"author":{"name":"Quantum","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda"},"headline":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum","datePublished":"2025-12-04T18:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/"},"wordCount":648,"publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg","articleSection":["Blog"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/","url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/","name":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum - Quantum | ITAD &amp; E-Waste Recycling","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#primaryimage"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg","datePublished":"2025-12-04T18:30:06+00:00","description":"Quantum s\u2019engage non seulement \u00e0 aider l\u2019environnement, mais aussi \u00e0 aider ses employ\u00e9s et ses m\u00e9thodes de d\u00e9veloppement.","breadcrumb":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#primaryimage","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2019\/12\/p-Cropped.jpg","width":1268,"height":634},{"@type":"BreadcrumbList","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/lamelioration-continue-detre-une-philosophie-directrice-chez-quantum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quantumlifecycle.com\/fr_CA\/"},{"@type":"ListItem","position":2,"name":"L\u2019am\u00e9lioration continue d\u2019\u00eatre une philosophie directrice chez Quantum"}]},{"@type":"WebSite","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","name":"Quantum | ITAD & E-Waste Recycling","description":"","publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quantumlifecycle.com\/fr_CA\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization","name":"Quantum Lifecycle Partners LP","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","width":2700,"height":848,"caption":"Quantum Lifecycle Partners LP"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda","name":"Quantum","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","caption":"Quantum"}}]}},"_links":{"self":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/comments?post=29398"}],"version-history":[{"count":0,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media\/29399"}],"wp:attachment":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media?parent=29398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/categories?post=29398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/tags?post=29398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}