{"id":29393,"date":"2025-12-04T13:27:27","date_gmt":"2025-12-04T18:27:27","guid":{"rendered":"https:\/\/quantumlifecycle.com\/uncategorized-fr_ca\/que-veut-on-dire-par-valeur\/"},"modified":"2025-12-04T13:27:27","modified_gmt":"2025-12-04T18:27:27","slug":"que-veut-on-dire-par-valeur","status":"publish","type":"post","link":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/","title":{"rendered":"Que veut-on dire par valeur?"},"content":{"rendered":"<p>La valeur prend plusieurs formes. Mais peu importe comment on le d\u00e9finit, Quantum a ce qu\u2019il te faut. En tant que partenaire pour un avenir durable, nous adoptons une approche en quatre volets pour la cr\u00e9ation de valeur, incluant la satisfaction constante de vos besoins en \u00e9limination des TI sur les plans financier, s\u00e9curitaire, environnemental et de commodit\u00e9.  <\/p>\n<h2><strong>Maximiser la valeur financi\u00e8re<\/strong><\/h2>\n<p>Beaucoup d\u2019entreprises ne r\u00e9alisent pas qu\u2019il y a de la valeur \u00e0 tirer au-del\u00e0 du fait de recycler gratuitement leur \u00e9quipement informatique ind\u00e9sirable.<\/p>\n<p>Si vous d\u00e9duisez r\u00e9guli\u00e8rement vos actifs en fin de vie, sachez que Quantum dispose de l\u2019infrastructure pour<a href=\"https:\/\/quantumlifecycle.com\/fr\/services\/reemploi-et-cannibalisation\/\"> remettre \u00e0 neuf, revendre et r\u00e9utiliser<\/a> de nombreux appareils retir\u00e9s \u2013 et peut vous restituer une partie de leur valeur.<\/p>\n<p>Votre organisation peut choisir de b\u00e9n\u00e9ficier de :<\/p>\n<ul>\n<li>Recevoir un gain net direct sous forme d\u2019un ch\u00e8que<\/li>\n<li>Faire en sorte que Quantum facilite un programme d\u2019achat pour employ\u00e9s en votre nom<\/li>\n<li>Faire don d\u2019une partie de toute valeur r\u00e9cup\u00e9r\u00e9e via une carte-cadeau caritative \u00e0<a href=\"https:\/\/qnovum.ca\/\"> notre boutique en ligne<\/a><\/li>\n<\/ul>\n<p>M\u00eame si vos actifs n\u2019ont aucune valeur de revente, l\u2019int\u00e9gration verticale de Quantum nous permet de minimiser ou d\u2019\u00e9liminer vos co\u00fbts d\u2019\u00e9limination gr\u00e2ce au recyclage des marchandises et \u00e0 l\u2019acc\u00e8s aux programmes provinciaux de gestion responsable. Nous pouvons m\u00eame payer pour vos mat\u00e9riaux de r\u00e9cup\u00e9ration dans certains cas. <\/p>\n<h2><strong>Offrir une valeur ax\u00e9e sur la s\u00e9curit\u00e9<\/strong><\/h2>\n<p>Quantum prend la s\u00e9curit\u00e9 de vos<a href=\"https:\/\/quantumlifecycle.com\/fr_CA\/whitepapers-fr_ca\/des-programmes-de-securite-des-donnees-qui-ont-du-sens\/\"> donn\u00e9es<\/a> tr\u00e8s au s\u00e9rieux. Conformes aux normes NAID AAA et R2 de recyclage, nous avons mis en place plusieurs politiques et proc\u00e9dures pour que rien ne vous emp\u00eache de dormir la nuit, notamment : <\/p>\n<ul>\n<li>Installations ITAD s\u00e9curis\u00e9es et surveill\u00e9es par CCTV<\/li>\n<li>V\u00e9rifications des ant\u00e9c\u00e9dents criminels pour tout le personnel de l\u2019\u00e9tablissement<\/li>\n<li>Camions scell\u00e9s et \u00e9quip\u00e9s de GPS<\/li>\n<\/ul>\n<p>Quantum offre m\u00eame une assurance responsabilit\u00e9 cybern\u00e9tique pour une tranquillit\u00e9 d\u2019esprit suppl\u00e9mentaire.<\/p>\n<p>Dans un monde o\u00f9 les donn\u00e9es sont devenues de plus en plus pr\u00e9cieuses \u2014 sans parler d\u2019une source potentielle de poursuites judiciaires \u2014 la valeur que Quantum apporte en termes de s\u00e9curit\u00e9 et<a href=\"https:\/\/quantumlifecycle.com\/fr_CA\/certifications\/\"> de certifications<\/a> est inestimable.<\/p>\n<h2><strong>Valoriser l\u2019environnement<\/strong><\/h2>\n<p>Quantum garantit que votre \u00e9quipement ind\u00e9sirable est toujours manipul\u00e9 de la mani\u00e8re la plus \u00e9cologique possible \u2013 en commen\u00e7ant par une \u00e9valuation pour la r\u00e9utilisation \u00e0 la discr\u00e9tion de votre organisation.<\/p>\n<p>Nous recommandons de prolonger la dur\u00e9e de vie de vos ordinateurs et de r\u00e9duire les gaz \u00e0 effet de serre en optant pour :<\/p>\n<ul>\n<li>Effacement s\u00e9curis\u00e9 et auditable des donn\u00e9es<\/li>\n<li>Remise \u00e0 neuf des appareils, et<\/li>\n<li>Revente de votre \u00e9quipement de travail<\/li>\n<\/ul>\n<p>Sinon, notre processus de recyclage s\u00e9curitaire et s\u00e9curis\u00e9 est votre meilleure option pour valoriser l\u2019environnement.<\/p>\n<p>Non seulement Quantum est approuv\u00e9 selon les normes nationales et mondiales les plus pertinentes sur les<a href=\"https:\/\/sustainableelectronics.org\/r2-standard\"> d\u00e9chets \u00e9lectroniques<\/a>, mais nous traitons plus de 50% des d\u00e9chets \u00e9lectroniques g\u00e9n\u00e9r\u00e9s au Canada. Vous n\u2019aurez pas \u00e0 vous inqui\u00e9ter que vos appareils finissent dans une d\u00e9charge ou export\u00e9s dans un pays o\u00f9 ils pourraient repr\u00e9senter un risque pour la sant\u00e9. <\/p>\n<h2><strong>La valeur de la commodit\u00e9<\/strong><\/h2>\n<p>\u00c0 quel point accordez-vous de l\u2019importance \u00e0 la commodit\u00e9? Avec Quantum, vous avez la possibilit\u00e9 d\u2019organiser des ramassages en ligne, par courriel ou par t\u00e9l\u00e9phone. Et comme nous exploitons plusieurs emplacements, travailler avec un seul membre d\u2019\u00e9quipe vous donne un acc\u00e8s automatique \u00e0 des services nationaux pour tous vos besoins de r\u00e9utilisation et de recyclage.  <\/p>\n<p>Une fois que votre service avec Quantum sera en place, vous ne vous demanderez jamais si nous allons \u00eatre pr\u00e9sents.<\/p>\n<p>On fait ce qu\u2019on dit qu\u2019on va faire, quand on dit qu\u2019on va le faire. Et m\u00eame si nous ne sommes pas parfaits, 99% du temps, nous faisons juste. Il est aussi rassurant de savoir qu\u2019en tant que service essentiel, Quantum reste op\u00e9rationnel en p\u00e9riode d\u2019incertitude.  <\/p>\n<h3><strong>Comparaison des fournisseurs de services<\/strong><\/h3>\n<p>Chez Quantum, nous comprenons que la d\u00e9finition de la valeur fluctue d\u2019une organisation \u00e0 l\u2019autre. C\u2019est pourquoi il est important de comparer les services<g id=\"gid_0\"> d\u2019\u00e9limination informatique<\/g> d\u2019un point de vue global. Si vous consid\u00e9rez la valeur sous toutes ses formes lorsque vous d\u00e9cidez d\u2019un fournisseur de services, vous constaterez que Quantum r\u00e9pond \u00e0 tous les aspects.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.<\/p>\n","protected":false},"author":3,"featured_media":29394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.","om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_metasync_otto_title":"","_metasync_otto_description":"","_metasync_otto_keywords":"","_metasync_otto_og_title":"","_metasync_otto_og_description":"","_metasync_otto_twitter_title":"","_metasync_otto_twitter_description":"","rank_math_title":"","rank_math_description":"","_aioseo_title":"","_aioseo_description":"","_metasync_seo_title":"","_metasync_seo_desc":"","_metasync_breadcrumb_title":"","_metasync_primary_category":0,"_metasync_primary_product_cat":0,"_metasync_otto_disabled":"","_metasync_hreflang":"","_metasync_plugin_sync_ts":"","_metasync_robots_advanced":"","footnotes":""},"categories":[47],"tags":[],"class_list":{"0":"post-29393","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blogue","8":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling<\/title>\n<meta name=\"description\" content=\"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:description\" content=\"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Quantum | ITAD &amp; E-Waste Recycling\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Quantum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Quantum\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/\"},\"author\":{\"name\":\"Quantum\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\"},\"headline\":\"Que veut-on dire par valeur?\",\"datePublished\":\"2025-12-04T18:27:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/\"},\"wordCount\":767,\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Value.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/\",\"name\":\"Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Value.jpg\",\"datePublished\":\"2025-12-04T18:27:27+00:00\",\"description\":\"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Value.jpg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Value.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/blogue\\\/que-veut-on-dire-par-valeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que veut-on dire par valeur?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#website\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"name\":\"Quantum | ITAD & E-Waste Recycling\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#organization\",\"name\":\"Quantum Lifecycle Partners LP\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/quantumlifecycle.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/logo.svg\",\"width\":2700,\"height\":848,\"caption\":\"Quantum Lifecycle Partners LP\"},\"image\":{\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/quantumlifecycle.com\\\/fr_CA\\\/#\\\/schema\\\/person\\\/0d31d3a02b64f5418ee4090adb8ebfda\",\"name\":\"Quantum\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g\",\"caption\":\"Quantum\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling","description":"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/","og_locale":"fr_CA","og_type":"article","og_title":"Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling","og_description":"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.","og_url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/","og_site_name":"Quantum | ITAD &amp; E-Waste Recycling","og_image":[{"width":1200,"height":800,"url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg","type":"image\/jpeg"}],"author":"Quantum","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Quantum","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#article","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/"},"author":{"name":"Quantum","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda"},"headline":"Que veut-on dire par valeur?","datePublished":"2025-12-04T18:27:27+00:00","mainEntityOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/"},"wordCount":767,"publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg","articleSection":["Blog"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/","url":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/","name":"Que veut-on dire par valeur? - Quantum | ITAD &amp; E-Waste Recycling","isPartOf":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#primaryimage"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#primaryimage"},"thumbnailUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg","datePublished":"2025-12-04T18:27:27+00:00","description":"L\u2019approche en quatre volets de Quantum pour la cr\u00e9ation de valeur garantit que vos besoins en \u00e9limination des TI sont satisfaits sur le plan financier, s\u00e9curitaire, environnemental et de commodit\u00e9.","breadcrumb":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#primaryimage","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/06\/Value.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/blogue\/que-veut-on-dire-par-valeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/quantumlifecycle.com\/fr_CA\/"},{"@type":"ListItem","position":2,"name":"Que veut-on dire par valeur?"}]},{"@type":"WebSite","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#website","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","name":"Quantum | ITAD & E-Waste Recycling","description":"","publisher":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quantumlifecycle.com\/fr_CA\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#organization","name":"Quantum Lifecycle Partners LP","url":"https:\/\/quantumlifecycle.com\/fr_CA\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/","url":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","contentUrl":"https:\/\/quantumlifecycle.com\/wp-content\/uploads\/2020\/01\/logo.svg","width":2700,"height":848,"caption":"Quantum Lifecycle Partners LP"},"image":{"@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/quantumlifecycle.com\/fr_CA\/#\/schema\/person\/0d31d3a02b64f5418ee4090adb8ebfda","name":"Quantum","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7468b0e5785e24e253d6b9a3ee6ca074db4a0872147499c96dc94254037a7508?s=96&d=mm&r=g","caption":"Quantum"}}]}},"_links":{"self":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/comments?post=29393"}],"version-history":[{"count":0,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/posts\/29393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media\/29394"}],"wp:attachment":[{"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/media?parent=29393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/categories?post=29393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantumlifecycle.com\/fr_CA\/wp-json\/wp\/v2\/tags?post=29393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}